{"id":26175,"date":"2024-05-15T15:23:52","date_gmt":"2024-05-15T15:23:52","guid":{"rendered":"https:\/\/hypergate.com\/?post_type=tribe_organizer&p=26175"},"modified":"2024-05-15T15:23:52","modified_gmt":"2024-05-15T15:23:52","slug":"dubai-world-trade-center","status":"publish","type":"tribe_organizer","link":"https:\/\/hypergate.com\/it\/organizzatore\/dubai-world-trade-center\/","title":{"rendered":"Dubai World Trade Center"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":159,"featured_media":0,"template":"","meta":{"footnotes":""},"class_list":["post-26175","tribe_organizer","type-tribe_organizer","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dubai World Trade Center | Hypergate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dubai World Trade Center | Hypergate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/\" \/>\n<meta property=\"og:site_name\" content=\"Hypergate\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hypergate.com\/wp-content\/uploads\/2018\/04\/Hypergate_logo_only.png\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hypergate_com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hypergate.com\\\/organizer\\\/dubai-world-trade-center\\\/\",\"url\":\"https:\\\/\\\/hypergate.com\\\/organizer\\\/dubai-world-trade-center\\\/\",\"name\":\"Dubai World Trade Center | Hypergate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hypergate.com\\\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hypergate.com\\\/organizer\\\/dubai-world-trade-center\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hypergate.com\\\/organizer\\\/dubai-world-trade-center\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hypergate.com\\\/organizer\\\/dubai-world-trade-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hypergate.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dubai World Trade Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hypergate.com\\\/#website\",\"url\":\"https:\\\/\\\/hypergate.com\\\/\",\"name\":\"Hypergate\",\"description\":\"Hypergate is a fast, secure and accessible Kerberos Single Sign-On (SSO) solution for Android and iOS\",\"publisher\":{\"@id\":\"https:\\\/\\\/hypergate.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hypergate.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hypergate.com\\\/#organization\",\"name\":\"Hypergate\",\"alternateName\":\"Hypergate Authenticator, Hypergate Files\",\"url\":\"https:\\\/\\\/hypergate.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hypergate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hypergate.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hypergate_logo_only.png\",\"contentUrl\":\"https:\\\/\\\/hypergate.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hypergate_logo_only.png\",\"width\":513,\"height\":513,\"caption\":\"Hypergate\"},\"image\":{\"@id\":\"https:\\\/\\\/hypergate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hypergate_com\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hypergate-ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dubai World Trade Center | Hypergate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/","og_locale":"it_IT","og_type":"article","og_title":"Dubai World Trade Center | Hypergate","og_url":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/","og_site_name":"Hypergate","og_image":[{"width":513,"height":513,"url":"https:\/\/hypergate.com\/wp-content\/uploads\/2018\/04\/Hypergate_logo_only.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@hypergate_com","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/","url":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/","name":"Dubai World Trade Center | Hypergate","isPartOf":{"@id":"https:\/\/hypergate.com\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hypergate.com\/organizer\/dubai-world-trade-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hypergate.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dubai World Trade Center"}]},{"@type":"WebSite","@id":"https:\/\/hypergate.com\/#website","url":"https:\/\/hypergate.com\/","name":"Hypergate","description":"Hypergate is a fast, secure and accessible Kerberos Single Sign-On (SSO) solution for Android and iOS","publisher":{"@id":"https:\/\/hypergate.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hypergate.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hypergate.com\/#organization","name":"Hypergate","alternateName":"Hypergate Authenticator, Hypergate Files","url":"https:\/\/hypergate.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hypergate.com\/#\/schema\/logo\/image\/","url":"https:\/\/hypergate.com\/wp-content\/uploads\/2018\/04\/Hypergate_logo_only.png","contentUrl":"https:\/\/hypergate.com\/wp-content\/uploads\/2018\/04\/Hypergate_logo_only.png","width":513,"height":513,"caption":"Hypergate"},"image":{"@id":"https:\/\/hypergate.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/hypergate_com","https:\/\/www.linkedin.com\/company\/hypergate-ch\/"]}]}},"_links":{"self":[{"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/tribe_organizer\/26175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/tribe_organizer"}],"about":[{"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/types\/tribe_organizer"}],"author":[{"embeddable":true,"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/users\/159"}],"version-history":[{"count":0,"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/tribe_organizer\/26175\/revisions"}],"wp:attachment":[{"href":"https:\/\/hypergate.com\/it\/wp-json\/wp\/v2\/media?parent=26175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}